{"id":1152,"date":"2018-11-30T11:38:14","date_gmt":"2018-11-30T10:38:14","guid":{"rendered":"http:\/\/896294.web09.swisscenter.com\/web\/?p=1152"},"modified":"2018-11-30T11:38:14","modified_gmt":"2018-11-30T10:38:14","slug":"deviation-ec-lanna-bisse-des-miriouges","status":"publish","type":"post","link":"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/","title":{"rendered":"D\u00e9viation EC Lanna-Bisse des Miriouges"},"content":{"rendered":"<table style=\"border: none; height: 176px; width: 52.2201%; border-collapse: none; border-style: none; border-color: none; background-color: none;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"border: none; width: 35.5264%; height: 24px; text-align: left;\"><strong>Co\u00fbt de l&rsquo;ouvrage :<\/strong><\/td>\n<td style=\"border: none; width: 45.8057%; height: 24px; text-align: right;\">230&rsquo;000.00 CHF<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"border: none; width: 35.5264%; height: 24px; text-align: left;\"><strong>Ann\u00e9e d&rsquo;ex\u00e9cution :<\/strong><\/td>\n<td style=\"border: none; width: 45.8057%; height: 24px; text-align: right;\">2018<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"border: none; width: 35.5264%; height: 24px;\"><strong>Ma\u00eetre de l&rsquo;ouvrage :<\/strong><\/td>\n<td style=\"border: none; width: 45.8057%; height: 24px; text-align: right;\">Administration communale de Lens<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"border: none; width: 35.5264%; height: 24px;\"><strong>Prestations effectu\u00e9es :<\/strong><\/td>\n<td style=\"border: none; width: 45.8057%; height: 24px; text-align: right;\">Mandat ing\u00e9nieur et g\u00e9om\u00e8tre<\/td>\n<\/tr>\n<tr style=\"height: 32px;\">\n<td style=\"border: none; width: 35.5264%; height: 32px; padding-left: 30px;\"><em>Projet de l&rsquo;ouvrage <span style=\"font-size: 20px;\"><strong>\u221a<\/strong><\/span><\/em><\/td>\n<td style=\"border: none; width: 45.8057%; height: 32px; text-align: right;\"><em>Ex\u00e9cution de l&rsquo;ouvrage <span style=\"font-size: 20px;\"><strong>\u221a<\/strong><\/span><\/em><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"border: none; width: 35.5264%; height: 24px; padding-left: 30px;\"><em>Appel d&rsquo;offres \/ soumissions <span style=\"font-size: 20px;\"><strong>\u221a<\/strong><\/span><\/em><\/td>\n<td style=\"border: none; width: 45.8057%; height: 24px; text-align: right;\"><em>Direction des travaux <span style=\"font-size: 20px;\"><strong>\u221a<\/strong><\/span><\/em><\/td>\n<\/tr>\n<tr style=\"border: none; height: 24px;\">\n<td style=\"border: none; width: 35.5264%; height: 24px; padding-left: 30px;\"><em>Projet d&rsquo;ex\u00e9cution <span style=\"font-size: 20px;\"><strong>\u221a<\/strong><\/span><\/em><\/td>\n<td style=\"border: none; width: 45.8057%; height: 24px; text-align: right;\"><em>Direction g\u00e9n\u00e9rale du projet <span style=\"font-size: 20px;\"><strong>\u221a<\/strong><\/span><br \/>\n<\/em><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Co\u00fbt de l&rsquo;ouvrage : 230&rsquo;000.00 CHF Ann\u00e9e d&rsquo;ex\u00e9cution : 2018 Ma\u00eetre de l&rsquo;ouvrage : Administration communale de Lens Prestations effectu\u00e9es : Mandat ing\u00e9nieur et g\u00e9om\u00e8tre Projet de l&rsquo;ouvrage \u221a Ex\u00e9cution de l&rsquo;ouvrage \u221a Appel d&rsquo;offres \/ soumissions \u221a Direction des travaux \u221a Projet d&rsquo;ex\u00e9cution \u221a Direction g\u00e9n\u00e9rale du projet \u221a<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1,32,4,35],"tags":[],"class_list":["post-1152","post","type-post","status-publish","format-standard","hentry","category-actualites","category-geometre","category-genie-civil-references","category-reseau-souterrain"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9viation EC Lanna-Bisse des Miriouges &#183; H\u00fcnerwadel &amp; H\u00e4berli Sion SA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9viation EC Lanna-Bisse des Miriouges &#183; H\u00fcnerwadel &amp; H\u00e4berli Sion SA\" \/>\n<meta property=\"og:description\" content=\"Co\u00fbt de l&rsquo;ouvrage : 230&rsquo;000.00 CHF Ann\u00e9e d&rsquo;ex\u00e9cution : 2018 Ma\u00eetre de l&rsquo;ouvrage : Administration communale de Lens Prestations effectu\u00e9es : Mandat ing\u00e9nieur et g\u00e9om\u00e8tre Projet de l&rsquo;ouvrage \u221a Ex\u00e9cution de l&rsquo;ouvrage \u221a Appel d&rsquo;offres \/ soumissions \u221a Direction des travaux \u221a Projet d&rsquo;ex\u00e9cution \u221a Direction g\u00e9n\u00e9rale du projet \u221a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/\" \/>\n<meta property=\"og:site_name\" content=\"H\u00fcnerwadel &amp; H\u00e4berli Sion SA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HHsionSA\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-30T10:38:14+00:00\" \/>\n<meta name=\"author\" content=\"hhsion1950\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"hhsion1950\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/\"},\"author\":{\"name\":\"hhsion1950\",\"@id\":\"https:\/\/hhsion.ch\/web\/#\/schema\/person\/5d1ef6952dab97eea7e308b7122f0923\"},\"headline\":\"D\u00e9viation EC Lanna-Bisse des Miriouges\",\"datePublished\":\"2018-11-30T10:38:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/\"},\"wordCount\":56,\"publisher\":{\"@id\":\"https:\/\/hhsion.ch\/web\/#organization\"},\"articleSection\":[\"Actualit\u00e9s\",\"G\u00e9om\u00e8tre\",\"Ing\u00e9nieur civil\",\"R\u00e9seau souterrain\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/\",\"url\":\"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/\",\"name\":\"D\u00e9viation EC Lanna-Bisse des Miriouges &#183; H\u00fcnerwadel &amp; H\u00e4berli Sion SA\",\"isPartOf\":{\"@id\":\"https:\/\/hhsion.ch\/web\/#website\"},\"datePublished\":\"2018-11-30T10:38:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/hhsion.ch\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9viation EC Lanna-Bisse des Miriouges\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hhsion.ch\/web\/#website\",\"url\":\"https:\/\/hhsion.ch\/web\/\",\"name\":\"H\u00fcnerwadel & H\u00e4berli Sion SA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/hhsion.ch\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hhsion.ch\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hhsion.ch\/web\/#organization\",\"name\":\"H\u00fcnerwadel & H\u00e4berli Sion SA\",\"url\":\"https:\/\/hhsion.ch\/web\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hhsion.ch\/web\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hhsion.ch\/web\/wp-content\/uploads\/2017\/09\/images.jpg\",\"contentUrl\":\"https:\/\/hhsion.ch\/web\/wp-content\/uploads\/2017\/09\/images.jpg\",\"width\":225,\"height\":225,\"caption\":\"H\u00fcnerwadel & H\u00e4berli Sion SA\"},\"image\":{\"@id\":\"https:\/\/hhsion.ch\/web\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/HHsionSA\/\",\"https:\/\/www.instagram.com\/hhsionsa\/\",\"https:\/\/www.linkedin.com\/company\/h-h-sion-sa\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/hhsion.ch\/web\/#\/schema\/person\/5d1ef6952dab97eea7e308b7122f0923\",\"name\":\"hhsion1950\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hhsion.ch\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/954f05d308ef9edab2a00891c03ea7134632d97137acfa846d45f5d3c8aa02f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/954f05d308ef9edab2a00891c03ea7134632d97137acfa846d45f5d3c8aa02f0?s=96&d=mm&r=g\",\"caption\":\"hhsion1950\"},\"url\":\"https:\/\/hhsion.ch\/web\/author\/hhsion1950\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9viation EC Lanna-Bisse des Miriouges &#183; H\u00fcnerwadel &amp; H\u00e4berli Sion SA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9viation EC Lanna-Bisse des Miriouges &#183; H\u00fcnerwadel &amp; H\u00e4berli Sion SA","og_description":"Co\u00fbt de l&rsquo;ouvrage : 230&rsquo;000.00 CHF Ann\u00e9e d&rsquo;ex\u00e9cution : 2018 Ma\u00eetre de l&rsquo;ouvrage : Administration communale de Lens Prestations effectu\u00e9es : Mandat ing\u00e9nieur et g\u00e9om\u00e8tre Projet de l&rsquo;ouvrage \u221a Ex\u00e9cution de l&rsquo;ouvrage \u221a Appel d&rsquo;offres \/ soumissions \u221a Direction des travaux \u221a Projet d&rsquo;ex\u00e9cution \u221a Direction g\u00e9n\u00e9rale du projet \u221a","og_url":"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/","og_site_name":"H\u00fcnerwadel &amp; H\u00e4berli Sion SA","article_publisher":"https:\/\/www.facebook.com\/HHsionSA\/","article_published_time":"2018-11-30T10:38:14+00:00","author":"hhsion1950","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"hhsion1950"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/#article","isPartOf":{"@id":"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/"},"author":{"name":"hhsion1950","@id":"https:\/\/hhsion.ch\/web\/#\/schema\/person\/5d1ef6952dab97eea7e308b7122f0923"},"headline":"D\u00e9viation EC Lanna-Bisse des Miriouges","datePublished":"2018-11-30T10:38:14+00:00","mainEntityOfPage":{"@id":"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/"},"wordCount":56,"publisher":{"@id":"https:\/\/hhsion.ch\/web\/#organization"},"articleSection":["Actualit\u00e9s","G\u00e9om\u00e8tre","Ing\u00e9nieur civil","R\u00e9seau souterrain"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/","url":"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/","name":"D\u00e9viation EC Lanna-Bisse des Miriouges &#183; H\u00fcnerwadel &amp; H\u00e4berli Sion SA","isPartOf":{"@id":"https:\/\/hhsion.ch\/web\/#website"},"datePublished":"2018-11-30T10:38:14+00:00","breadcrumb":{"@id":"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hhsion.ch\/web\/deviation-ec-lanna-bisse-des-miriouges\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/hhsion.ch\/web\/"},{"@type":"ListItem","position":2,"name":"D\u00e9viation EC Lanna-Bisse des Miriouges"}]},{"@type":"WebSite","@id":"https:\/\/hhsion.ch\/web\/#website","url":"https:\/\/hhsion.ch\/web\/","name":"H\u00fcnerwadel & H\u00e4berli Sion SA","description":"","publisher":{"@id":"https:\/\/hhsion.ch\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hhsion.ch\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hhsion.ch\/web\/#organization","name":"H\u00fcnerwadel & H\u00e4berli Sion SA","url":"https:\/\/hhsion.ch\/web\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hhsion.ch\/web\/#\/schema\/logo\/image\/","url":"https:\/\/hhsion.ch\/web\/wp-content\/uploads\/2017\/09\/images.jpg","contentUrl":"https:\/\/hhsion.ch\/web\/wp-content\/uploads\/2017\/09\/images.jpg","width":225,"height":225,"caption":"H\u00fcnerwadel & H\u00e4berli Sion SA"},"image":{"@id":"https:\/\/hhsion.ch\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HHsionSA\/","https:\/\/www.instagram.com\/hhsionsa\/","https:\/\/www.linkedin.com\/company\/h-h-sion-sa\/"]},{"@type":"Person","@id":"https:\/\/hhsion.ch\/web\/#\/schema\/person\/5d1ef6952dab97eea7e308b7122f0923","name":"hhsion1950","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hhsion.ch\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/954f05d308ef9edab2a00891c03ea7134632d97137acfa846d45f5d3c8aa02f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/954f05d308ef9edab2a00891c03ea7134632d97137acfa846d45f5d3c8aa02f0?s=96&d=mm&r=g","caption":"hhsion1950"},"url":"https:\/\/hhsion.ch\/web\/author\/hhsion1950\/"}]}},"_links":{"self":[{"href":"https:\/\/hhsion.ch\/web\/wp-json\/wp\/v2\/posts\/1152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hhsion.ch\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hhsion.ch\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hhsion.ch\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hhsion.ch\/web\/wp-json\/wp\/v2\/comments?post=1152"}],"version-history":[{"count":1,"href":"https:\/\/hhsion.ch\/web\/wp-json\/wp\/v2\/posts\/1152\/revisions"}],"predecessor-version":[{"id":1153,"href":"https:\/\/hhsion.ch\/web\/wp-json\/wp\/v2\/posts\/1152\/revisions\/1153"}],"wp:attachment":[{"href":"https:\/\/hhsion.ch\/web\/wp-json\/wp\/v2\/media?parent=1152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hhsion.ch\/web\/wp-json\/wp\/v2\/categories?post=1152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hhsion.ch\/web\/wp-json\/wp\/v2\/tags?post=1152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}